{"id":16100,"date":"2021-12-17T15:50:55","date_gmt":"2021-12-17T18:50:55","guid":{"rendered":"https:\/\/larealidaddelaplata.com.ar\/?p=16100"},"modified":"2021-12-17T16:56:40","modified_gmt":"2021-12-17T19:56:40","slug":"mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios","status":"publish","type":"post","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/","title":{"rendered":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios"},"content":{"rendered":"\n<p>Bajo el lema \u201cuna pelota para cada pibx y un potrero en cada barrio\u201d, la agrupaci\u00f3n Gimnasia es Pueblo realizar\u00e1 por segundo a\u00f1o consecutivo la \u201cMisi\u00f3n Navidad Tripera\u201d con el objetivo de entregar el pr\u00f3ximo 23 de diciembre m\u00e1s de 100 pelotas de f\u00fatbol en los distintos barrios populares de La Plata, Berisso y Ensenada.<\/p>\n\n\n\n<p>Para lograrlo, los socios e hinchas que integran la Agrupaci\u00f3n tripera lanzaron una novedosa metodolog\u00eda para recaudar los fondos necesarios para los obsequios: se puede ingresar a <a href=\"http:\/\/www.misionnavidadtripera.com.ar\">www.misionnavidadtripera.com.ar<\/a> y colaborar con la compra de una rifa virtual a $200 y participar de un sorteo de 22 incre\u00edbles premios que se sortear\u00e1n un d\u00eda antes de la entrega. De manera alternativa, ponen a disposici\u00f3n la cuenta de Instagram de la Agrupaci\u00f3n (<strong>@gimnasiaespueblo<\/strong>) para colaborar con otra forma de pago:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/164.90.252.231\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.49-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-16103\" srcset=\"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.49-1-1024x682.jpeg 1024w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.49-1-300x200.jpeg 300w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.49-1-768x512.jpeg 768w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.49-1-150x100.jpeg 150w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.49-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u201cNos propusimos esta misi\u00f3n porque creemos en los potreros como herramientas de inclusi\u00f3n y formaci\u00f3n, en el deporte como escuela de vida y, sobre todo, creemos en los pibes\u201d resaltaron los organizadores de la iniciativa solidaria.<\/p>\n\n\n\n<p>Y agregaron: \u201cQueremos un club que no escape a sus ra\u00edces, que meta las patas en el barro y en el barrio. Un club con conciencia social y trabajo colectivo, que forme filiales y potreros que contengan a lxs pibxs de cada barrio y lxs acerque al club. Sabemos que no hay Maradonas sin potreros\u201d\u201d.<\/p>\n\n\n\n<p>Cabe destacar que la primera misi\u00f3n se realiz\u00f3 en diciembre del a\u00f1o pasado y consisti\u00f3 en la entrega de canastas navide\u00f1as para m\u00e1s de 100 familias de barrios populares tras haber recaudado fondos con la misma l\u00f3gica: la ayuda de triperos y triperas que compraron rifas solidarias o donaron alg\u00fan premio para el sorteo.<\/p>\n\n\n\n<p>Por \u00faltimo, desde \u201cGimnasia es Pueblo\u201d dejaron un mensaje para lxs hinchas del lobo: \u201cNo dudamos del coraz\u00f3n solidario del Pueblo Tripero \u00a1\ud835\udde6\ud835\udde8\ud835\udde0\ud835\uddd4\ud835\udde7\ud835\uddd8 \ud835\uddd4 \ud835\udddf\ud835\uddd4 \ud835\udde0\ud835\udddc\ud835\udde6\ud835\udddc\ud835\udde2\ud835\udde1!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/164.90.252.231\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.47-1024x1024.jpeg\" alt=\"\" class=\"wp-image-16104\" srcset=\"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.47-1024x1024.jpeg 1024w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.47-300x300.jpeg 300w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.47-150x150.jpeg 150w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.47-768x768.jpeg 768w, https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.47.jpeg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el lema \u201cuna pelota para cada pibx y un potrero en cada barrio\u201d, la agrupaci\u00f3n Gimnasia es Pueblo realizar\u00e1 por segundo a\u00f1o consecutivo la \u201cMisi\u00f3n Navidad Tripera\u201d con el objetivo de entregar el pr\u00f3ximo 23 de diciembre m\u00e1s de 100 pelotas de f\u00fatbol en los distintos barrios populares de La Plata, Berisso y Ensenada. Para lograrlo, los socios e hinchas que integran la Agrupaci\u00f3n tripera lanzaron una novedosa metodolog\u00eda&hellip;<\/p>\n","protected":false},"author":4,"featured_media":16102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11],"tags":[26,3233],"class_list":["post-16100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gimnasia","tag-gimnasia","tag-navidad-tripera"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bajo el lema \u201cuna pelota para cada pibx y un potrero en cada barrio\u201d, la agrupaci\u00f3n Gimnasia es Pueblo realizar\u00e1 por segundo a\u00f1o consecutivo la \u201cMisi\u00f3n Navidad Tripera\u201d con el objetivo de entregar el pr\u00f3ximo 23 de diciembre m\u00e1s de 100 pelotas de f\u00fatbol en los distintos barrios populares de La Plata, Berisso y Ensenada.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"luis\"\/>\n\t<meta name=\"keywords\" content=\"gimnasia,navidad tripera\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#article\",\"name\":\"\\u201cMisi\\u00f3n Navidad Tripera\\u201d: entregar\\u00e1n m\\u00e1s de 100 pelotas en los barrios | larealidaddelaplata.com.ar\",\"headline\":\"\\u201cMisi\\u00f3n Navidad Tripera\\u201d: entregar\\u00e1n m\\u00e1s de 100 pelotas en los barrios\",\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/luis\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-17-at-14.43.48.jpeg\",\"width\":495,\"height\":330},\"datePublished\":\"2021-12-17T15:50:55-03:00\",\"dateModified\":\"2021-12-17T16:56:40-03:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#webpage\"},\"articleSection\":\"Gimnasia, Gimnasia, navidad tripera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"name\":\"Gimnasia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"position\":3,\"name\":\"Gimnasia\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#listItem\",\"name\":\"\\u201cMisi\\u00f3n Navidad Tripera\\u201d: entregar\\u00e1n m\\u00e1s de 100 pelotas en los barrios\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#listItem\",\"position\":4,\"name\":\"\\u201cMisi\\u00f3n Navidad Tripera\\u201d: entregar\\u00e1n m\\u00e1s de 100 pelotas en los barrios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"name\":\"Gimnasia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Diseno-sin-titulo-1-1.png\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#organizationLogo\",\"width\":1920,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/luis\\\/#author\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/luis\\\/\",\"name\":\"luis\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c016b0af8e5d16df530d0b2353eaa80e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"luis\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#webpage\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/\",\"name\":\"\\u201cMisi\\u00f3n Navidad Tripera\\u201d: entregar\\u00e1n m\\u00e1s de 100 pelotas en los barrios | larealidaddelaplata.com.ar\",\"description\":\"Bajo el lema \\u201cuna pelota para cada pibx y un potrero en cada barrio\\u201d, la agrupaci\\u00f3n Gimnasia es Pueblo realizar\\u00e1 por segundo a\\u00f1o consecutivo la \\u201cMisi\\u00f3n Navidad Tripera\\u201d con el objetivo de entregar el pr\\u00f3ximo 23 de diciembre m\\u00e1s de 100 pelotas de f\\u00fatbol en los distintos barrios populares de La Plata, Berisso y Ensenada.\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/luis\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/luis\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/WhatsApp-Image-2021-12-17-at-14.43.48.jpeg\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#mainImage\",\"width\":495,\"height\":330},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2021\\\/12\\\/17\\\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\\\/#mainImage\"},\"datePublished\":\"2021-12-17T15:50:55-03:00\",\"dateModified\":\"2021-12-17T16:56:40-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios | larealidaddelaplata.com.ar","description":"Bajo el lema \u201cuna pelota para cada pibx y un potrero en cada barrio\u201d, la agrupaci\u00f3n Gimnasia es Pueblo realizar\u00e1 por segundo a\u00f1o consecutivo la \u201cMisi\u00f3n Navidad Tripera\u201d con el objetivo de entregar el pr\u00f3ximo 23 de diciembre m\u00e1s de 100 pelotas de f\u00fatbol en los distintos barrios populares de La Plata, Berisso y Ensenada.","canonical_url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"gimnasia,navidad tripera","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#article","name":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios | larealidaddelaplata.com.ar","headline":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios","author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/luis\/#author"},"publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.48.jpeg","width":495,"height":330},"datePublished":"2021-12-17T15:50:55-03:00","dateModified":"2021-12-17T16:56:40-03:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#webpage"},"isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#webpage"},"articleSection":"Gimnasia, Gimnasia, navidad tripera"},{"@type":"BreadcrumbList","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","position":1,"name":"Home","item":"https:\/\/larealidaddelaplata.com.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","name":"Gimnasia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","position":3,"name":"Gimnasia","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#listItem","name":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#listItem","position":4,"name":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios","previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","name":"Gimnasia"}}]},{"@type":"Organization","@id":"https:\/\/larealidaddelaplata.com.ar\/#organization","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","url":"https:\/\/larealidaddelaplata.com.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/01\/cropped-Diseno-sin-titulo-1-1.png","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#organizationLogo","width":1920,"height":355},"image":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/luis\/#author","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/luis\/","name":"luis","image":{"@type":"ImageObject","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c016b0af8e5d16df530d0b2353eaa80e?s=96&d=mm&r=g","width":96,"height":96,"caption":"luis"}},{"@type":"WebPage","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#webpage","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/","name":"\u201cMisi\u00f3n Navidad Tripera\u201d: entregar\u00e1n m\u00e1s de 100 pelotas en los barrios | larealidaddelaplata.com.ar","description":"Bajo el lema \u201cuna pelota para cada pibx y un potrero en cada barrio\u201d, la agrupaci\u00f3n Gimnasia es Pueblo realizar\u00e1 por segundo a\u00f1o consecutivo la \u201cMisi\u00f3n Navidad Tripera\u201d con el objetivo de entregar el pr\u00f3ximo 23 de diciembre m\u00e1s de 100 pelotas de f\u00fatbol en los distintos barrios populares de La Plata, Berisso y Ensenada.","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#website"},"breadcrumb":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#breadcrumblist"},"author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/luis\/#author"},"creator":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/luis\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-17-at-14.43.48.jpeg","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#mainImage","width":495,"height":330},"primaryImageOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2021\/12\/17\/mision-navidad-tripera-entregaran-mas-de-100-pelotas-en-los-barrios\/#mainImage"},"datePublished":"2021-12-17T15:50:55-03:00","dateModified":"2021-12-17T16:56:40-03:00"},{"@type":"WebSite","@id":"https:\/\/larealidaddelaplata.com.ar\/#website","url":"https:\/\/larealidaddelaplata.com.ar\/","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","inLanguage":"es-AR","publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"}}]}},"aioseo_meta_data":{"post_id":"16100","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"aioseo-article-63a48a9307c04","slug":"article","graphName":"Article","label":"Article","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-17 18:26:20","updated":"2022-12-22 16:49:23","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16100"}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16100"}],"version-history":[{"count":0,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16102"}],"wp:attachment":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}