{"id":16795,"date":"2022-01-19T15:01:22","date_gmt":"2022-01-19T18:01:22","guid":{"rendered":"https:\/\/larealidaddelaplata.com.ar\/?p=16795"},"modified":"2022-01-19T15:01:25","modified_gmt":"2022-01-19T18:01:25","slug":"gimnasia-acordo-la-llegada-de-cristian-tarragona","status":"publish","type":"post","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/","title":{"rendered":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona"},"content":{"rendered":"\n<p>El &#8220;lobo&#8221; de N\u00e9stor &#8220;Pipo&#8221; Gorosito confirm\u00f3 el arribo de un nuevo fichaje. Se trata del delantero Cristian Tarragona proveniente de V\u00e9lez llega en condici\u00f3n de jugador libre.<\/p>\n\n\n\n<p>El delantero de 30 a\u00f1os disput\u00f3 un total de 67 partidos en un a\u00f1o y medio y convirti\u00f3 12 goles en su paso por V\u00e9lez.<\/p>\n\n\n\n<p>Por otra parte, <strong>Tarragona firmar\u00e1 por un a\u00f1o<\/strong>, con una opci\u00f3n de compra, que una vez resuelto ese monto, se sumar\u00e1 a la pretemporada en Mar del Plata.<\/p>\n\n\n\n<p>La prioridad del Lobo en todos los \u00faltimos mercados de pases, fue encontrar a un nueve goleador, rol que no encontr\u00f3 en Lucas Barrios, Nicol\u00e1s Cont\u00edn, Rodrigo Holgado y\u00a0Eric Ram\u00edrez, entre tantos otros. Ahora,\u00a0<strong>el entrenador cree que consigui\u00f3\u00a0al rompe redes.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mir\u00e1 lo mejor del delantero:<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/youtu.be\/Z_rfbe-kCeM\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00a1ZURDAZO DE TARRAGONA Y GOL DEL FORT\u00cdN!  V\u00e9lez vs Boca Juniors (2-0) Fecha 18-Torneo de la Liga 2021\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/4P1djHVDaI4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Cristian Tarragona (1-0) V\u00e9lez vs Estudiantes LP | Fecha 3 Grupo B - Fase Complement. Copa Maradona\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/0R0EOB2tDOs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00a1GOL DE V\u00c9LEZ! Cristian Tarragona | Newell&#039;s vs V\u00e9lez (0-2) | Fecha 15 - Torneo de la Liga 2021\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/78_g1Vt-q7k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El &#8220;lobo&#8221; de N\u00e9stor &#8220;Pipo&#8221; Gorosito confirm\u00f3 el arribo de un nuevo fichaje. Se trata del delantero Cristian Tarragona proveniente de V\u00e9lez llega en condici\u00f3n de jugador libre. El delantero de 30 a\u00f1os disput\u00f3 un total de 67 partidos en un a\u00f1o y medio y convirti\u00f3 12 goles en su paso por V\u00e9lez. Por otra parte, Tarragona firmar\u00e1 por un a\u00f1o, con una opci\u00f3n de compra, que una vez resuelto&hellip;<\/p>\n","protected":false},"author":6,"featured_media":16796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,11],"tags":[26,21],"class_list":["post-16795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-gimnasia","tag-gimnasia","tag-la-plata"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El &quot;lobo&quot; de N\u00e9stor &quot;Pipo&quot; Gorosito confirm\u00f3 el arribo de un nuevo fichaje. Se trata del delantero Cristian Tarragona proveniente de V\u00e9lez llega en condici\u00f3n de jugador libre. El delantero de 30 a\u00f1os disput\u00f3 un total de 67 partidos en un a\u00f1o y medio y convirti\u00f3 12 goles en su paso por V\u00e9lez. Por otra\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Julian I\"\/>\n\t<meta name=\"keywords\" content=\"gimnasia,la plata\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#article\",\"name\":\"Gimnasia acord\\u00f3 la llegada de Cristian Tarragona | larealidaddelaplata.com.ar\",\"headline\":\"Gimnasia acord\\u00f3 la llegada de Cristian Tarragona\",\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/tarragona-velezjpg.jpg-e1642615276590.webp\",\"width\":800,\"height\":500},\"datePublished\":\"2022-01-19T15:01:22-03:00\",\"dateModified\":\"2022-01-19T15:01:25-03:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#webpage\"},\"articleSection\":\"Deportes, Gimnasia, Gimnasia, La Plata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"name\":\"Gimnasia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"position\":3,\"name\":\"Gimnasia\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#listItem\",\"name\":\"Gimnasia acord\\u00f3 la llegada de Cristian Tarragona\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#listItem\",\"position\":4,\"name\":\"Gimnasia acord\\u00f3 la llegada de Cristian Tarragona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"name\":\"Gimnasia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Diseno-sin-titulo-1-1.png\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#organizationLogo\",\"width\":1920,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/\",\"name\":\"Julian I\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f5e6017926e0aaca87fb5bdd97543f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Julian I\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#webpage\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/\",\"name\":\"Gimnasia acord\\u00f3 la llegada de Cristian Tarragona | larealidaddelaplata.com.ar\",\"description\":\"El \\\"lobo\\\" de N\\u00e9stor \\\"Pipo\\\" Gorosito confirm\\u00f3 el arribo de un nuevo fichaje. Se trata del delantero Cristian Tarragona proveniente de V\\u00e9lez llega en condici\\u00f3n de jugador libre. El delantero de 30 a\\u00f1os disput\\u00f3 un total de 67 partidos en un a\\u00f1o y medio y convirti\\u00f3 12 goles en su paso por V\\u00e9lez. Por otra\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/tarragona-velezjpg.jpg-e1642615276590.webp\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#mainImage\",\"width\":800,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2022\\\/01\\\/19\\\/gimnasia-acordo-la-llegada-de-cristian-tarragona\\\/#mainImage\"},\"datePublished\":\"2022-01-19T15:01:22-03:00\",\"dateModified\":\"2022-01-19T15:01:25-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona | larealidaddelaplata.com.ar","description":"El \"lobo\" de N\u00e9stor \"Pipo\" Gorosito confirm\u00f3 el arribo de un nuevo fichaje. Se trata del delantero Cristian Tarragona proveniente de V\u00e9lez llega en condici\u00f3n de jugador libre. El delantero de 30 a\u00f1os disput\u00f3 un total de 67 partidos en un a\u00f1o y medio y convirti\u00f3 12 goles en su paso por V\u00e9lez. Por otra","canonical_url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"gimnasia,la plata","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#article","name":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona | larealidaddelaplata.com.ar","headline":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona","author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2022\/01\/tarragona-velezjpg.jpg-e1642615276590.webp","width":800,"height":500},"datePublished":"2022-01-19T15:01:22-03:00","dateModified":"2022-01-19T15:01:25-03:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#webpage"},"isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#webpage"},"articleSection":"Deportes, Gimnasia, Gimnasia, La Plata"},{"@type":"BreadcrumbList","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","position":1,"name":"Home","item":"https:\/\/larealidaddelaplata.com.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","name":"Gimnasia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","position":3,"name":"Gimnasia","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#listItem","name":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#listItem","position":4,"name":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona","previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","name":"Gimnasia"}}]},{"@type":"Organization","@id":"https:\/\/larealidaddelaplata.com.ar\/#organization","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","url":"https:\/\/larealidaddelaplata.com.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/01\/cropped-Diseno-sin-titulo-1-1.png","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#organizationLogo","width":1920,"height":355},"image":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/","name":"Julian I","image":{"@type":"ImageObject","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/41f5e6017926e0aaca87fb5bdd97543f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Julian I"}},{"@type":"WebPage","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#webpage","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/","name":"Gimnasia acord\u00f3 la llegada de Cristian Tarragona | larealidaddelaplata.com.ar","description":"El \"lobo\" de N\u00e9stor \"Pipo\" Gorosito confirm\u00f3 el arribo de un nuevo fichaje. Se trata del delantero Cristian Tarragona proveniente de V\u00e9lez llega en condici\u00f3n de jugador libre. El delantero de 30 a\u00f1os disput\u00f3 un total de 67 partidos en un a\u00f1o y medio y convirti\u00f3 12 goles en su paso por V\u00e9lez. Por otra","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#website"},"breadcrumb":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#breadcrumblist"},"author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"creator":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2022\/01\/tarragona-velezjpg.jpg-e1642615276590.webp","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#mainImage","width":800,"height":500},"primaryImageOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2022\/01\/19\/gimnasia-acordo-la-llegada-de-cristian-tarragona\/#mainImage"},"datePublished":"2022-01-19T15:01:22-03:00","dateModified":"2022-01-19T15:01:25-03:00"},{"@type":"WebSite","@id":"https:\/\/larealidaddelaplata.com.ar\/#website","url":"https:\/\/larealidaddelaplata.com.ar\/","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","inLanguage":"es-AR","publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"}}]}},"aioseo_meta_data":{"post_id":"16795","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"aioseo-article-63a8963e14ac0","slug":"article","graphName":"Article","label":"Article","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-19 17:43:31","updated":"2022-12-25 18:28:14","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16795"}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16795"}],"version-history":[{"count":0,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16796"}],"wp:attachment":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}