{"id":28027,"date":"2023-02-27T14:02:07","date_gmt":"2023-02-27T17:02:07","guid":{"rendered":"https:\/\/larealidaddelaplata.com.ar\/?p=28027"},"modified":"2023-02-27T14:02:13","modified_gmt":"2023-02-27T17:02:13","slug":"gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5","status":"publish","type":"post","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/","title":{"rendered":"Gimnasia visita a Barracas en el cierre de la fecha 5"},"content":{"rendered":"\n<p>La quinta jornada de la\u00a0<strong>Liga Profesional de F\u00fatbol<\/strong>\u00a0llega a su fin con tres encuentros a lo largo del lunes. A la espera del duelo entre Racing y Lan\u00fas, la punta est\u00e1 compartida entre el\u00a0<em>Granate<\/em>,\u00a0<strong>Defensa y Justicia<\/strong>,<strong>\u00a0Talleres de C\u00f3rdoba<\/strong>y\u00a0<strong>San Lorenzo<\/strong>\u00a0al tener 12 unidades cada uno.\u00a0<\/p>\n\n\n\n<p><strong>Barracas Central<\/strong>\u00a0recibir\u00e1 a<strong>\u00a0Gimnasia y Esgrima La Plata\u00a0<\/strong>en un partido en el que ambos equipos buscar\u00e1n su segunda victoria en la\u00a0<strong>Liga Profesional de Futbol<\/strong>. El encuentro correspondiente a la quinta fecha se jugar\u00e1 desde las 17 en el estadio<em>Claudio Chiqui Tapia<\/em>, ser\u00e1 arbitrado por Nicol\u00e1s Lamolina y televisado por la\u00a0<em>TV P\u00fablica<\/em>.<\/p>\n\n\n\n<p>El\u00a0<em>Lobo<\/em> tiene cuatro unidades y adem\u00e1s viene de ser eliminado por\u00a0<strong>Excursionistas<\/strong>, en uno de los batacazos de la Copa Argentina. Para recuperarse an\u00edmicamente del golpe que supuso la temprana salida del torneo federal, buscar\u00e1 sumar su segunda victoria consecutiva ya que viene de vencer de local a\u00a0<strong>Instituto\u00a0<\/strong>por 2 a 0.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Posibles formaciones<\/h2>\n\n\n\n<p><strong>Barracas Central:&nbsp;<\/strong>Andr\u00e9s Desabato; Maximiliano Rodr\u00edguez, Nicol\u00e1s Capraro, Francisco \u00c1lvarez, Juan Ignacio D\u00edaz; Mauro Peinipil; Carlos Arce; Iv\u00e1n Tapia, Maximiliano Puig; Marcos Ben\u00edtez y Bruno Sep\u00falveda. DT: Rodolfo De Paoli.<\/p>\n\n\n\n<p><strong>Gimnasia:&nbsp;<\/strong>Tom\u00e1s Durso; Guillermo Enrique, Leonardo Morales, Felipe Sanchez, Mat\u00edas Melluso; Agust\u00edn Bolivar o Ignacio Miramon, Antonio Napolitano, Alexis Steimbach, Eric Ram\u00edrez, Alan Sosa y Nicol\u00e1s Cont\u00edn. DT: Sebasti\u00e1n Romero.<\/p>\n\n\n\n<p><strong>Estadio:&nbsp;<\/strong>Claudio Fabi\u00e1n Tapia<\/p>\n\n\n\n<p><strong>Hora:&nbsp;<\/strong>17.00<\/p>\n\n\n\n<p><strong>\u00c1rbitro:&nbsp;<\/strong>Nicol\u00e1s Lamolina<\/p>\n\n\n\n<p><strong>TV:<\/strong><em><strong>&nbsp;<\/strong><\/em><em>TV P\u00fablica<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La quinta jornada de la\u00a0Liga Profesional de F\u00fatbol\u00a0llega a su fin con tres encuentros a lo largo del lunes. A la espera del duelo entre Racing y Lan\u00fas, la punta est\u00e1 compartida entre el\u00a0Granate,\u00a0Defensa y Justicia,\u00a0Talleres de C\u00f3rdobay\u00a0San Lorenzo\u00a0al tener 12 unidades cada uno.\u00a0 Barracas Central\u00a0recibir\u00e1 a\u00a0Gimnasia y Esgrima La Plata\u00a0en un partido en el que ambos equipos buscar\u00e1n su segunda victoria en la\u00a0Liga Profesional de Futbol. El encuentro correspondiente&hellip;<\/p>\n","protected":false},"author":6,"featured_media":27963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,11],"tags":[26],"class_list":["post-28027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-gimnasia","tag-gimnasia"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La quinta jornada de la Liga Profesional de F\u00fatbol llega a su fin con tres encuentros a lo largo del lunes. A la espera del duelo entre Racing y Lan\u00fas, la punta est\u00e1 compartida entre el Granate, Defensa y Justicia, Talleres de C\u00f3rdobay San Lorenzo al tener 12 unidades cada uno. Barracas Central recibir\u00e1 a Gimnasia y Esgrima La Plata en un partido en el\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Julian I\"\/>\n\t<meta name=\"keywords\" content=\"gimnasia\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#article\",\"name\":\"Gimnasia visita a Barracas en el cierre de la fecha 5 | larealidaddelaplata.com.ar\",\"headline\":\"Gimnasia visita a Barracas en el cierre de la fecha 5\",\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/gelp-v-exc3.jpg\",\"width\":800,\"height\":500},\"datePublished\":\"2023-02-27T14:02:07-03:00\",\"dateModified\":\"2023-02-27T14:02:13-03:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#webpage\"},\"articleSection\":\"Deportes, Gimnasia, Gimnasia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"name\":\"Gimnasia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"position\":3,\"name\":\"Gimnasia\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#listItem\",\"name\":\"Gimnasia visita a Barracas en el cierre de la fecha 5\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#listItem\",\"position\":4,\"name\":\"Gimnasia visita a Barracas en el cierre de la fecha 5\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/deportes\\\/gimnasia\\\/#listItem\",\"name\":\"Gimnasia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Diseno-sin-titulo-1-1.png\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#organizationLogo\",\"width\":1920,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/\",\"name\":\"Julian I\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f5e6017926e0aaca87fb5bdd97543f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Julian I\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#webpage\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/\",\"name\":\"Gimnasia visita a Barracas en el cierre de la fecha 5 | larealidaddelaplata.com.ar\",\"description\":\"La quinta jornada de la Liga Profesional de F\\u00fatbol llega a su fin con tres encuentros a lo largo del lunes. A la espera del duelo entre Racing y Lan\\u00fas, la punta est\\u00e1 compartida entre el Granate, Defensa y Justicia, Talleres de C\\u00f3rdobay San Lorenzo al tener 12 unidades cada uno. Barracas Central recibir\\u00e1 a Gimnasia y Esgrima La Plata en un partido en el\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/gelp-v-exc3.jpg\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#mainImage\",\"width\":800,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2023\\\/02\\\/27\\\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\\\/#mainImage\"},\"datePublished\":\"2023-02-27T14:02:07-03:00\",\"dateModified\":\"2023-02-27T14:02:13-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Gimnasia visita a Barracas en el cierre de la fecha 5 | larealidaddelaplata.com.ar","description":"La quinta jornada de la Liga Profesional de F\u00fatbol llega a su fin con tres encuentros a lo largo del lunes. A la espera del duelo entre Racing y Lan\u00fas, la punta est\u00e1 compartida entre el Granate, Defensa y Justicia, Talleres de C\u00f3rdobay San Lorenzo al tener 12 unidades cada uno. Barracas Central recibir\u00e1 a Gimnasia y Esgrima La Plata en un partido en el","canonical_url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"gimnasia","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#article","name":"Gimnasia visita a Barracas en el cierre de la fecha 5 | larealidaddelaplata.com.ar","headline":"Gimnasia visita a Barracas en el cierre de la fecha 5","author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2023\/02\/gelp-v-exc3.jpg","width":800,"height":500},"datePublished":"2023-02-27T14:02:07-03:00","dateModified":"2023-02-27T14:02:13-03:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#webpage"},"isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#webpage"},"articleSection":"Deportes, Gimnasia, Gimnasia"},{"@type":"BreadcrumbList","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","position":1,"name":"Home","item":"https:\/\/larealidaddelaplata.com.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","name":"Gimnasia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","position":3,"name":"Gimnasia","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#listItem","name":"Gimnasia visita a Barracas en el cierre de la fecha 5"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#listItem","position":4,"name":"Gimnasia visita a Barracas en el cierre de la fecha 5","previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/deportes\/gimnasia\/#listItem","name":"Gimnasia"}}]},{"@type":"Organization","@id":"https:\/\/larealidaddelaplata.com.ar\/#organization","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","url":"https:\/\/larealidaddelaplata.com.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/01\/cropped-Diseno-sin-titulo-1-1.png","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#organizationLogo","width":1920,"height":355},"image":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/","name":"Julian I","image":{"@type":"ImageObject","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/41f5e6017926e0aaca87fb5bdd97543f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Julian I"}},{"@type":"WebPage","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#webpage","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/","name":"Gimnasia visita a Barracas en el cierre de la fecha 5 | larealidaddelaplata.com.ar","description":"La quinta jornada de la Liga Profesional de F\u00fatbol llega a su fin con tres encuentros a lo largo del lunes. A la espera del duelo entre Racing y Lan\u00fas, la punta est\u00e1 compartida entre el Granate, Defensa y Justicia, Talleres de C\u00f3rdobay San Lorenzo al tener 12 unidades cada uno. Barracas Central recibir\u00e1 a Gimnasia y Esgrima La Plata en un partido en el","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#website"},"breadcrumb":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#breadcrumblist"},"author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"creator":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2023\/02\/gelp-v-exc3.jpg","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#mainImage","width":800,"height":500},"primaryImageOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2023\/02\/27\/gimnasia-visita-a-barracas-en-el-cierre-de-la-fecha-5\/#mainImage"},"datePublished":"2023-02-27T14:02:07-03:00","dateModified":"2023-02-27T14:02:13-03:00"},{"@type":"WebSite","@id":"https:\/\/larealidaddelaplata.com.ar\/#website","url":"https:\/\/larealidaddelaplata.com.ar\/","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","inLanguage":"es-AR","publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"}}]}},"aioseo_meta_data":{"post_id":"28027","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-02-27 16:54:16","updated":"2023-02-27 17:02:15","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/28027"}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=28027"}],"version-history":[{"count":2,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/28027\/revisions"}],"predecessor-version":[{"id":28029,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/28027\/revisions\/28029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media\/27963"}],"wp:attachment":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=28027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=28027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=28027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}