{"id":42660,"date":"2026-05-21T15:37:53","date_gmt":"2026-05-21T18:37:53","guid":{"rendered":"https:\/\/larealidaddelaplata.com.ar\/?p=42660"},"modified":"2026-05-21T15:37:56","modified_gmt":"2026-05-21T18:37:56","slug":"alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus","status":"publish","type":"post","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/","title":{"rendered":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En un contexto de creciente preocupaci\u00f3n por el fuerte aumento de los casos de hantavirus en la provincia de Buenos Aires, la comunidad educativa de La Plata se encuentra en estado de alerta. Las familias de los alumnos de la <strong>Escuela Normal N\u00b03<\/strong> y la <strong>Primaria N\u00b01 &#8220;Francisco A. Berra&#8221;<\/strong>, instituciones ubicadas en la calle 8 entre 57 y 58, denunciaron la alarmante aparici\u00f3n de ratas y alacranes dentro de los establecimientos y exigieron la r\u00e1pida intervenci\u00f3n de las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el relato de los propios denunciantes, estos preocupantes episodios comenzaron a registrarse durante la \u00faltima semana y ya afectan a distintos sectores de los dos edificios, a los cuales asisten diariamente cientos de chicos provenientes de diferentes puntos de la ciudad. Los testimonios recabados precisan que los alacranes fueron hallados principalmente en las \u00e1reas de nivel Inicial y Primaria, mientras que en la zona destinada a la Secundaria se detect\u00f3 la presencia de los roedores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la gravedad de la situaci\u00f3n y la l\u00f3gica inquietud de los padres, desde la conducci\u00f3n de la instituci\u00f3n enviaron un comunicado oficial para informar sobre las medidas adoptadas. En el escrito detallaron que un equipo de <strong>especialistas del Conicet<\/strong> y profesionales del \u00e1rea de <strong>Toxicolog\u00eda<\/strong> ya recorrieron las instalaciones afectadas. Adem\u00e1s, explicaron que estos equipos t\u00e9cnicos se encuentran asesorando a los directivos para definir los pasos a seguir con el objetivo de erradicar las plagas y garantizar la seguridad sanitaria de todos los estudiantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un contexto de creciente preocupaci\u00f3n por el fuerte aumento de los casos de hantavirus en la provincia de Buenos Aires, la comunidad educativa de La Plata se encuentra en estado de alerta. Las familias de los alumnos de la Escuela Normal N\u00b03 y la Primaria N\u00b01 &#8220;Francisco A. Berra&#8221;, instituciones ubicadas en la calle 8 entre 57 y 58, denunciaron la alarmante aparici\u00f3n de ratas y alacranes dentro de&hellip;<\/p>\n","protected":false},"author":6,"featured_media":42661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-42660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-plata"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"En un contexto de creciente preocupaci\u00f3n por el fuerte aumento de los casos de hantavirus en la provincia de Buenos Aires, la comunidad educativa de La Plata se encuentra en estado de alerta. Las familias de los alumnos de la Escuela Normal N\u00b03 y la Primaria N\u00b01 &quot;Francisco A. Berra&quot;, instituciones ubicadas en la calle\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Julian I\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#article\",\"name\":\"Alarma en dos escuelas de La Plata: denuncian la aparici\\u00f3n de ratas y alacranes en pleno brote de hantavirus | larealidaddelaplata.com.ar\",\"headline\":\"Alarma en dos escuelas de La Plata: denuncian la aparici\\u00f3n de ratas y alacranes en pleno brote de hantavirus\",\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ZOGGFASVYJBVVAOTSCERE6EOYE-e1779388663350.avif\",\"width\":800,\"height\":450},\"datePublished\":\"2026-05-21T15:37:53-03:00\",\"dateModified\":\"2026-05-21T15:37:56-03:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#webpage\"},\"articleSection\":\"La Plata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/la-plata\\\/#listItem\",\"name\":\"La Plata\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/la-plata\\\/#listItem\",\"position\":2,\"name\":\"La Plata\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/la-plata\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#listItem\",\"name\":\"Alarma en dos escuelas de La Plata: denuncian la aparici\\u00f3n de ratas y alacranes en pleno brote de hantavirus\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#listItem\",\"position\":3,\"name\":\"Alarma en dos escuelas de La Plata: denuncian la aparici\\u00f3n de ratas y alacranes en pleno brote de hantavirus\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/la-plata\\\/#listItem\",\"name\":\"La Plata\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Diseno-sin-titulo-1-1.png\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#organizationLogo\",\"width\":1920,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/\",\"name\":\"Julian I\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7771209082b3e5bb400c4977362cbab150b08c7199fffcd6a227c0b2fbe17c9c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Julian I\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#webpage\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/\",\"name\":\"Alarma en dos escuelas de La Plata: denuncian la aparici\\u00f3n de ratas y alacranes en pleno brote de hantavirus | larealidaddelaplata.com.ar\",\"description\":\"En un contexto de creciente preocupaci\\u00f3n por el fuerte aumento de los casos de hantavirus en la provincia de Buenos Aires, la comunidad educativa de La Plata se encuentra en estado de alerta. Las familias de los alumnos de la Escuela Normal N\\u00b03 y la Primaria N\\u00b01 \\\"Francisco A. Berra\\\", instituciones ubicadas en la calle\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/julian_ibarrola\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ZOGGFASVYJBVVAOTSCERE6EOYE-e1779388663350.avif\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#mainImage\",\"width\":800,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/05\\\/21\\\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\\\/#mainImage\"},\"datePublished\":\"2026-05-21T15:37:53-03:00\",\"dateModified\":\"2026-05-21T15:37:56-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus | larealidaddelaplata.com.ar","description":"En un contexto de creciente preocupaci\u00f3n por el fuerte aumento de los casos de hantavirus en la provincia de Buenos Aires, la comunidad educativa de La Plata se encuentra en estado de alerta. Las familias de los alumnos de la Escuela Normal N\u00b03 y la Primaria N\u00b01 \"Francisco A. Berra\", instituciones ubicadas en la calle","canonical_url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#article","name":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus | larealidaddelaplata.com.ar","headline":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus","author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2026\/05\/ZOGGFASVYJBVVAOTSCERE6EOYE-e1779388663350.avif","width":800,"height":450},"datePublished":"2026-05-21T15:37:53-03:00","dateModified":"2026-05-21T15:37:56-03:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#webpage"},"isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#webpage"},"articleSection":"La Plata"},{"@type":"BreadcrumbList","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","position":1,"name":"Home","item":"https:\/\/larealidaddelaplata.com.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/la-plata\/#listItem","name":"La Plata"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/la-plata\/#listItem","position":2,"name":"La Plata","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/la-plata\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#listItem","name":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#listItem","position":3,"name":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus","previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/la-plata\/#listItem","name":"La Plata"}}]},{"@type":"Organization","@id":"https:\/\/larealidaddelaplata.com.ar\/#organization","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","url":"https:\/\/larealidaddelaplata.com.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/01\/cropped-Diseno-sin-titulo-1-1.png","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#organizationLogo","width":1920,"height":355},"image":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/","name":"Julian I","image":{"@type":"ImageObject","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/7771209082b3e5bb400c4977362cbab150b08c7199fffcd6a227c0b2fbe17c9c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Julian I"}},{"@type":"WebPage","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#webpage","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/","name":"Alarma en dos escuelas de La Plata: denuncian la aparici\u00f3n de ratas y alacranes en pleno brote de hantavirus | larealidaddelaplata.com.ar","description":"En un contexto de creciente preocupaci\u00f3n por el fuerte aumento de los casos de hantavirus en la provincia de Buenos Aires, la comunidad educativa de La Plata se encuentra en estado de alerta. Las familias de los alumnos de la Escuela Normal N\u00b03 y la Primaria N\u00b01 \"Francisco A. Berra\", instituciones ubicadas en la calle","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#website"},"breadcrumb":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#breadcrumblist"},"author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"creator":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/julian_ibarrola\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2026\/05\/ZOGGFASVYJBVVAOTSCERE6EOYE-e1779388663350.avif","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#mainImage","width":800,"height":450},"primaryImageOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/05\/21\/alarma-en-dos-escuelas-de-la-plata-denuncian-la-aparicion-de-ratas-y-alacranes-en-pleno-brote-de-hantavirus\/#mainImage"},"datePublished":"2026-05-21T15:37:53-03:00","dateModified":"2026-05-21T15:37:56-03:00"},{"@type":"WebSite","@id":"https:\/\/larealidaddelaplata.com.ar\/#website","url":"https:\/\/larealidaddelaplata.com.ar\/","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","inLanguage":"es-AR","publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"}}]}},"aioseo_meta_data":{"post_id":"42660","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-21 18:03:38","updated":"2026-05-21 18:37:58","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/42660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=42660"}],"version-history":[{"count":1,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/42660\/revisions"}],"predecessor-version":[{"id":42662,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/42660\/revisions\/42662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media\/42661"}],"wp:attachment":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=42660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=42660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=42660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}