{"id":43132,"date":"2026-07-15T09:51:24","date_gmt":"2026-07-15T12:51:24","guid":{"rendered":"https:\/\/larealidaddelaplata.com.ar\/?p=43132"},"modified":"2026-07-15T09:51:26","modified_gmt":"2026-07-15T12:51:26","slug":"carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero","status":"publish","type":"post","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/","title":{"rendered":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\u00f3n de potrero&#8221;"},"content":{"rendered":"\n<p>El\u00a0Centro de ex Combatientes Islas Malvinas\u00a0escribi\u00f3 una carta para la Selecci\u00f3n Argentina en la previa a la semifinal del Mundial que debatir\u00e1 contra Inglaterra ma\u00f1ana mi\u00e9rcoles 15 de julio.<\/p>\n\n\n\n<p>&#8220;Jueguen con el coraz\u00f3n de potrero&#8221;, les dedicaron concientes del componente hist\u00f3rico y emocional que mueve el partido en el marco del reclamo que el pa\u00eds mantiene para recuperar la soberan\u00eda de las islas y precisamente, atravesado por la Guerra de Malvinas en la que los por entonces j\u00f3venes fueron convocados en 1982.<\/p>\n\n\n\n<p>&#8220;Verlos jugar en este Mundial nos llena de un orgullo profundo. Nos conmueve c\u00f3mo representan a nuestro f\u00fatbol: compitiendo hasta el l\u00edmite, sin rendirse jam\u00e1s y buscando la gloria hasta el \u00faltimo suspiro.&nbsp;<mark>Hace un tiempo lograron algo que parec\u00eda imposible: que los argentinos volvamos a mirar a la Selecci\u00f3n como un punto de encuentro, como un punto de pertenencia del cual nos sentimos profundamente orgullosos<\/mark>&#8220;, comenzaron escribiendo.<\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DawYGLHkZ68\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/DawYGLHkZ68\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/DawYGLHkZ68\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de CECIM La Plata (@cecimlaplata)<\/a><\/p><\/div><\/blockquote>\n<script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<p>Los veteranos se\u00f1alaron que &#8220;ahora se viene un partido de transcendencia enorme&#8221;. &#8220;Una semifinal del mundo es gigante por s\u00ed sola; sumarle el rival que est\u00e1 en frente la vuelve hist\u00f3rica&#8221;, expresaron al tiempo que les pidieron que no se olviden de algo, en consonancia con las recientes\u00a0declaraciones\u00a0de\u00a0<strong>Lionel Scaloni<\/strong>: &#8220;sigue siendo s\u00f3lo un partido de f\u00fatbol. Nada m\u00e1s y nada menos&#8221;.<\/p>\n\n\n\n<p><mark>&#8220;Sobre los enfrentamientos con los ingleses, queremos decirles algo con el coraz\u00f3n en la mano: Diego ya nos veng\u00f3&#8221;<\/mark>, transmitieron en referencia a y asegurando que ya no quedan &#8220;deudas deportivas que saldar con ellos&#8221;, les pidieron que salgan a la cancha a hacer lo que mejor saben hacer: &#8220;jugar al f\u00fatbol&#8221;.<\/p>\n\n\n\n<p>&#8220;Sabemos que ustedes entienden perfectamente que para nosotros no es un partido cualquiera. Pero les pedimos que mantengan la calma. Jueguen con ese esp\u00edritu de potrero, con la resiliencia y la rebeld\u00eda que el futbolista argentino lleva desde la cuna que es nuestra marca registrada en el mundo&#8221;, afirmaron.<\/p>\n\n\n\n<p>&#8220;Todo un pa\u00eds va a estar empujando detr\u00e1s de ustedes. Sabemos que van a dar la vida, que van a correr sobre el cansancio y el traj\u00edn del torneo. Pero jueguen liberados: el resultado de un partido no los va a definir&#8221;, siguieron y cerraron con emoci\u00f3n: &#8220;El bronce y el amor eterno del pueblo ya lo tienen ganado&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Centro de ex Combatientes Islas Malvinas\u00a0escribi\u00f3 una carta para la Selecci\u00f3n Argentina en la previa a la semifinal del Mundial que debatir\u00e1 contra Inglaterra ma\u00f1ana mi\u00e9rcoles 15 de julio. &#8220;Jueguen con el coraz\u00f3n de potrero&#8221;, les dedicaron concientes del componente hist\u00f3rico y emocional que mueve el partido en el marco del reclamo que el pa\u00eds mantiene para recuperar la soberan\u00eda de las islas y precisamente, atravesado por la Guerra de&hellip;<\/p>\n","protected":false},"author":3,"featured_media":16459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-43132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Centro de ex Combatientes Islas Malvinas escribi\u00f3 una carta para la Selecci\u00f3n Argentina en la previa a la semifinal del Mundial que debatir\u00e1 contra Inglaterra ma\u00f1ana mi\u00e9rcoles 15 de julio. &quot;Jueguen con el coraz\u00f3n de potrero&quot;, les dedicaron concientes del componente hist\u00f3rico y emocional que mueve el partido en el marco del reclamo que el pa\u00eds\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Riso\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#article\",\"name\":\"Carta de los ex combatientes de Malvinas a la Selecci\\u00f3n ante la semifinal con Inglaterra: \\u201cJueguen con el coraz\\u00f3n de potrero\\u201d | larealidaddelaplata.com.ar\",\"headline\":\"Carta de los ex combatientes de Malvinas a la Selecci\\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\\u00f3n de potrero&#8221;\",\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/riso\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/maradona-86-2.jpg\",\"width\":800,\"height\":500},\"datePublished\":\"2026-07-15T09:51:24-03:00\",\"dateModified\":\"2026-07-15T09:51:26-03:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#webpage\"},\"articleSection\":\"Provincia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/provincia\\\/#listItem\",\"name\":\"Provincia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/provincia\\\/#listItem\",\"position\":2,\"name\":\"Provincia\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/provincia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#listItem\",\"name\":\"Carta de los ex combatientes de Malvinas a la Selecci\\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\\u00f3n de potrero&#8221;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#listItem\",\"position\":3,\"name\":\"Carta de los ex combatientes de Malvinas a la Selecci\\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\\u00f3n de potrero&#8221;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/category\\\/provincia\\\/#listItem\",\"name\":\"Provincia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Diseno-sin-titulo-1-1.png\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#organizationLogo\",\"width\":1920,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/riso\\\/#author\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/riso\\\/\",\"name\":\"Riso\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f86b15997587b8b42e79894dd009a150?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Riso\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#webpage\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/\",\"name\":\"Carta de los ex combatientes de Malvinas a la Selecci\\u00f3n ante la semifinal con Inglaterra: \\u201cJueguen con el coraz\\u00f3n de potrero\\u201d | larealidaddelaplata.com.ar\",\"description\":\"El Centro de ex Combatientes Islas Malvinas escribi\\u00f3 una carta para la Selecci\\u00f3n Argentina en la previa a la semifinal del Mundial que debatir\\u00e1 contra Inglaterra ma\\u00f1ana mi\\u00e9rcoles 15 de julio. \\\"Jueguen con el coraz\\u00f3n de potrero\\\", les dedicaron concientes del componente hist\\u00f3rico y emocional que mueve el partido en el marco del reclamo que el pa\\u00eds\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/riso\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/author\\\/riso\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/maradona-86-2.jpg\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#mainImage\",\"width\":800,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\\\/#mainImage\"},\"datePublished\":\"2026-07-15T09:51:24-03:00\",\"dateModified\":\"2026-07-15T09:51:26-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: \u201cJueguen con el coraz\u00f3n de potrero\u201d | larealidaddelaplata.com.ar","description":"El Centro de ex Combatientes Islas Malvinas escribi\u00f3 una carta para la Selecci\u00f3n Argentina en la previa a la semifinal del Mundial que debatir\u00e1 contra Inglaterra ma\u00f1ana mi\u00e9rcoles 15 de julio. \"Jueguen con el coraz\u00f3n de potrero\", les dedicaron concientes del componente hist\u00f3rico y emocional que mueve el partido en el marco del reclamo que el pa\u00eds","canonical_url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#article","name":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: \u201cJueguen con el coraz\u00f3n de potrero\u201d | larealidaddelaplata.com.ar","headline":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\u00f3n de potrero&#8221;","author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/riso\/#author"},"publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/maradona-86-2.jpg","width":800,"height":500},"datePublished":"2026-07-15T09:51:24-03:00","dateModified":"2026-07-15T09:51:26-03:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#webpage"},"isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#webpage"},"articleSection":"Provincia"},{"@type":"BreadcrumbList","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","position":1,"name":"Home","item":"https:\/\/larealidaddelaplata.com.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/provincia\/#listItem","name":"Provincia"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/provincia\/#listItem","position":2,"name":"Provincia","item":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/provincia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#listItem","name":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\u00f3n de potrero&#8221;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#listItem","position":3,"name":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: &#8220;Jueguen con el coraz\u00f3n de potrero&#8221;","previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/category\/provincia\/#listItem","name":"Provincia"}}]},{"@type":"Organization","@id":"https:\/\/larealidaddelaplata.com.ar\/#organization","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","url":"https:\/\/larealidaddelaplata.com.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/01\/cropped-Diseno-sin-titulo-1-1.png","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#organizationLogo","width":1920,"height":355},"image":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/riso\/#author","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/riso\/","name":"Riso","image":{"@type":"ImageObject","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f86b15997587b8b42e79894dd009a150?s=96&d=mm&r=g","width":96,"height":96,"caption":"Riso"}},{"@type":"WebPage","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#webpage","url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/","name":"Carta de los ex combatientes de Malvinas a la Selecci\u00f3n ante la semifinal con Inglaterra: \u201cJueguen con el coraz\u00f3n de potrero\u201d | larealidaddelaplata.com.ar","description":"El Centro de ex Combatientes Islas Malvinas escribi\u00f3 una carta para la Selecci\u00f3n Argentina en la previa a la semifinal del Mundial que debatir\u00e1 contra Inglaterra ma\u00f1ana mi\u00e9rcoles 15 de julio. \"Jueguen con el coraz\u00f3n de potrero\", les dedicaron concientes del componente hist\u00f3rico y emocional que mueve el partido en el marco del reclamo que el pa\u00eds","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#website"},"breadcrumb":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#breadcrumblist"},"author":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/riso\/#author"},"creator":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/author\/riso\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/12\/maradona-86-2.jpg","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#mainImage","width":800,"height":500},"primaryImageOfPage":{"@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/2026\/07\/15\/carta-de-los-ex-combatientes-de-malvinas-a-la-seleccion-ante-la-semifinal-con-inglaterra-jueguen-con-el-corazon-de-potrero\/#mainImage"},"datePublished":"2026-07-15T09:51:24-03:00","dateModified":"2026-07-15T09:51:26-03:00"},{"@type":"WebSite","@id":"https:\/\/larealidaddelaplata.com.ar\/#website","url":"https:\/\/larealidaddelaplata.com.ar\/","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","inLanguage":"es-AR","publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"}}]}},"aioseo_meta_data":{"post_id":"43132","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 12:49:10","updated":"2026-07-15 12:51:27","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/43132"}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=43132"}],"version-history":[{"count":1,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/43132\/revisions"}],"predecessor-version":[{"id":43133,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/43132\/revisions\/43133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16459"}],"wp:attachment":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=43132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=43132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=43132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}