{"id":2229,"count":1,"description":"","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/tag\/mario-quintana\/","name":"Mario Quintana","slug":"mario-quintana","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/larealidaddelaplata.com.ar\/index.php\/tag\/mario-quintana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2229\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/larealidaddelaplata.com.ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/tag\\\/mario-quintana\\\/#listItem\",\"name\":\"Mario Quintana\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/index.php\\\/tag\\\/mario-quintana\\\/#listItem\",\"position\":2,\"name\":\"Mario Quintana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2229\\\/#collectionpage\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2229\\\/\",\"name\":\"Mario Quintana | La Realidad de La Plata\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2229\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Diseno-sin-titulo-1-1.png\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2229\\\/#organizationLogo\",\"width\":1920,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2229\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/\",\"name\":\"La Realidad de La Plata\",\"description\":\"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/larealidaddelaplata.com.ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mario Quintana | La Realidad de La Plata","description":"","canonical_url":"https:\/\/larealidaddelaplata.com.ar\/index.php\/tag\/mario-quintana\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/larealidaddelaplata.com.ar\/wp-json\/wp\/v2\/tags\/2229\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","position":1,"name":"Home","item":"https:\/\/larealidaddelaplata.com.ar","nextItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/tag\/mario-quintana\/#listItem","name":"Mario Quintana"}},{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar\/index.php\/tag\/mario-quintana\/#listItem","position":2,"name":"Mario Quintana","previousItem":{"@type":"ListItem","@id":"https:\/\/larealidaddelaplata.com.ar#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/larealidaddelaplata.com.ar\/wp-json\/wp\/v2\/tags\/2229\/#collectionpage","url":"https:\/\/larealidaddelaplata.com.ar\/wp-json\/wp\/v2\/tags\/2229\/","name":"Mario Quintana | La Realidad de La Plata","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#website"},"breadcrumb":{"@id":"https:\/\/larealidaddelaplata.com.ar\/wp-json\/wp\/v2\/tags\/2229\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/larealidaddelaplata.com.ar\/#organization","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","url":"https:\/\/larealidaddelaplata.com.ar\/","logo":{"@type":"ImageObject","url":"https:\/\/larealidaddelaplata.com.ar\/wp-content\/uploads\/2021\/01\/cropped-Diseno-sin-titulo-1-1.png","@id":"https:\/\/larealidaddelaplata.com.ar\/wp-json\/wp\/v2\/tags\/2229\/#organizationLogo","width":1920,"height":355},"image":{"@id":"https:\/\/larealidaddelaplata.com.ar\/wp-json\/wp\/v2\/tags\/2229\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/larealidaddelaplata.com.ar\/#website","url":"https:\/\/larealidaddelaplata.com.ar\/","name":"La Realidad de La Plata","description":"Tu portal de noticias sobre la realidad la Provincia de Buenos Aires y La Plata","inLanguage":"es-AR","publisher":{"@id":"https:\/\/larealidaddelaplata.com.ar\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags\/2229"}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts?tags=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}