{"id":3675,"count":1,"description":"","link":"https:\/\/larealidaddelaplata.com.ar\/index.php\/tag\/aniversario-festejos\/","name":"Aniversario festejos","slug":"aniversario-festejos","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags\/3675"}],"collection":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/larealidaddelaplata.com.ar\/index.php\/wp-json\/wp\/v2\/posts?tags=3675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}